{"id":779,"date":"2022-01-24T17:51:05","date_gmt":"2022-01-24T17:51:05","guid":{"rendered":"https:\/\/pasteldfeira.com.br\/cardapio\/?post_type=product&#038;p=779"},"modified":"2022-02-04T18:58:30","modified_gmt":"2022-02-04T18:58:30","slug":"pastel-de-presunto-e-queijo-normal-cru-12-unidades","status":"publish","type":"product","link":"https:\/\/pasteldfeira.com.br\/cardapio\/produto\/pastel-de-presunto-e-queijo-normal-cru-12-unidades\/","title":{"rendered":"Pastel de Presunto e Queijo Normal Cru 12 unidades"},"content":{"rendered":"<p>Pastel Cru para assar ou fritar em sua casa para festas, ou eventos. Leve nosso sabor para toda a fam\u00edlia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pastel Cru para assar ou fritar em sua casa para festas, ou eventos. Leve nosso sabor para toda a fam\u00edlia.<\/p>\n","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[286],"product_tag":[339,340,288,337,338,342,291,280,296,297,292,25,287,34,88,293,294,298,295,341],"class_list":{"0":"post-779","1":"product","2":"type-product","3":"status-publish","5":"product_cat-combos","6":"product_tag-aberto-agora","7":"product_tag-comida","8":"product_tag-feira","9":"product_tag-lanche","10":"product_tag-lanche-em-tupa","11":"product_tag-lugar-para-comer","12":"product_tag-massa-crua","13":"product_tag-massa-de-pastel","14":"product_tag-massa-para-fritar","15":"product_tag-massapara-assar","16":"product_tag-mini-pastel","17":"product_tag-pastel","18":"product_tag-pastel-cru","19":"product_tag-pastel-dfeira","20":"product_tag-pastel-de-feira","21":"product_tag-pastel-grande","22":"product_tag-pastel-medio","23":"product_tag-pastel-para-festas","24":"product_tag-pastel-pequeno","25":"product_tag-restaurante","27":"first","28":"instock","29":"shipping-taxable","30":"purchasable","31":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/pasteldfeira.com.br\/cardapio\/wp-json\/wp\/v2\/product\/779","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pasteldfeira.com.br\/cardapio\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/pasteldfeira.com.br\/cardapio\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/pasteldfeira.com.br\/cardapio\/wp-json\/wp\/v2\/comments?post=779"}],"wp:attachment":[{"href":"https:\/\/pasteldfeira.com.br\/cardapio\/wp-json\/wp\/v2\/media?parent=779"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/pasteldfeira.com.br\/cardapio\/wp-json\/wp\/v2\/product_brand?post=779"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/pasteldfeira.com.br\/cardapio\/wp-json\/wp\/v2\/product_cat?post=779"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/pasteldfeira.com.br\/cardapio\/wp-json\/wp\/v2\/product_tag?post=779"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}