{"id":759,"date":"2022-01-24T17:23:45","date_gmt":"2022-01-24T17:23:45","guid":{"rendered":"https:\/\/pasteldfeira.com.br\/cardapio\/?post_type=product&#038;p=759"},"modified":"2022-02-04T19:03:18","modified_gmt":"2022-02-04T19:03:18","slug":"pastel-de-calabresa-gourmet-cru-24-unidades","status":"publish","type":"product","link":"https:\/\/pasteldfeira.com.br\/cardapio\/produto\/pastel-de-calabresa-gourmet-cru-24-unidades\/","title":{"rendered":"Pastel de Calabresa Gourmet Cru 24 unidades"},"content":{"rendered":"<p>Pastel Cru para assar ou fritar em sua casa para festas, ou eventos. Leve nosso sabor para toda a fam\u00edlia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pastel Cru para assar ou fritar em sua casa para festas, ou eventos. Leve nosso sabor para toda a fam\u00edlia.<\/p>\n","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[286],"product_tag":[339,340,288,337,338,342,291,280,296,297,292,25,287,34,88,293,294,298,295,341],"class_list":{"0":"post-759","1":"product","2":"type-product","3":"status-publish","5":"product_cat-combos","6":"product_tag-aberto-agora","7":"product_tag-comida","8":"product_tag-feira","9":"product_tag-lanche","10":"product_tag-lanche-em-tupa","11":"product_tag-lugar-para-comer","12":"product_tag-massa-crua","13":"product_tag-massa-de-pastel","14":"product_tag-massa-para-fritar","15":"product_tag-massapara-assar","16":"product_tag-mini-pastel","17":"product_tag-pastel","18":"product_tag-pastel-cru","19":"product_tag-pastel-dfeira","20":"product_tag-pastel-de-feira","21":"product_tag-pastel-grande","22":"product_tag-pastel-medio","23":"product_tag-pastel-para-festas","24":"product_tag-pastel-pequeno","25":"product_tag-restaurante","27":"first","28":"instock","29":"shipping-taxable","30":"purchasable","31":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/pasteldfeira.com.br\/cardapio\/wp-json\/wp\/v2\/product\/759","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pasteldfeira.com.br\/cardapio\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/pasteldfeira.com.br\/cardapio\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/pasteldfeira.com.br\/cardapio\/wp-json\/wp\/v2\/comments?post=759"}],"wp:attachment":[{"href":"https:\/\/pasteldfeira.com.br\/cardapio\/wp-json\/wp\/v2\/media?parent=759"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/pasteldfeira.com.br\/cardapio\/wp-json\/wp\/v2\/product_brand?post=759"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/pasteldfeira.com.br\/cardapio\/wp-json\/wp\/v2\/product_cat?post=759"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/pasteldfeira.com.br\/cardapio\/wp-json\/wp\/v2\/product_tag?post=759"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}